{"id":2079,"date":"2020-06-16T14:11:58","date_gmt":"2020-06-16T12:11:58","guid":{"rendered":"https:\/\/www.stabnau.com\/business-next-level\/"},"modified":"2020-12-09T11:01:22","modified_gmt":"2020-12-09T10:01:22","slug":"business-next-level","status":"publish","type":"post","link":"https:\/\/stabnau.com\/de\/business-next-level\/","title":{"rendered":"Business Next Level"},"content":{"rendered":"<p><\/p>\n<p>Die COVID-19-Pandemie hat uns bewusst gemacht, dass <strong>unsere Gesundheit sehr wichtig ist.<\/strong> Unsere Wirtschaft, der Motor unserer Gesellschaft, wurde hart getroffen und jetzt ist es an der Zeit, wieder auf Kurs zu kommen. Wir k\u00f6nnen so weitermachen, wie wir es bisher getan haben, oder einige Dinge verbessern. Bis jetzt basierte unser Wirtschaftssystem ausschlie\u00dflich auf monet\u00e4ren Werten, auf Geld. Wir brauchen Geld, es ist der Fluss, der die Wirtschaft zum Funktionieren bringt. Aber wie alles andere sind Extreme nie gut. Wir m\u00fcssen das richtige Gleichgewicht finden, denn es darf nicht zum Nachteil von Mensch und Umwelt sein. Wir sind alle miteinander verbunden und voneinander abh\u00e4ngig. Die Freiheit der einen endet dort, wo die Freiheit der anderen beginnt. Was f\u00fcr eine Art von Spezies w\u00e4ren wir, wenn wir weiterhin nat\u00fcrliche Ressourcen pl\u00fcndern, die globale Erw\u00e4rmung weiter beschleunigen, Wasser- und Nahrungsmittelknappheit schaffen, soziale Ungleichheiten f\u00fcr individualistische profitorientierte Interessen vertiefen und ins All fliehen wollten?<\/p>\n<p><\/p>\n<p><\/p>\n<p>Es gibt keinen Widerspruch oder Gegensatz zwischen \u00d6konomie, Sozialem und \u00d6kologie: diese drei Elemente bilden ein Ganzes. <strong>Die Wirtschaft wird von den Menschen f\u00fcr die Menschen gestaltet und muss seinen Lebensraum die Umwelt sch\u00fctzen und erhalten.&nbsp;<\/strong><\/p>\n<p><\/p>\n<p><\/p>\n<p><strong>Von der Konfrontation zur Zusammenarbeit<\/strong>. Bisher wurde der Handel zu oft als Machtkampf betrachtet. Es gibt einen Gewinner und einen Verlierer. Die Finanzwelt und die Aktienm\u00e4rkte repr\u00e4sentieren dies mit einem Stier und einem B\u00e4ren. Aber die Welt ist nicht schwarz und wei\u00df. Sie besteht auch aus einer Vielzahl von Farben. Die besten Gesch\u00e4fte sind diejenigen, bei denen es zwei Gewinner gibt (WIN-WIN). Wie beim Verkauf, bei dem der K\u00e4ufer das Produkt findet, das seinem Bedarf entspricht und der Verk\u00e4ufer, der sein Produkt verkauft. Neben der materiellen Zufriedenheit gibt es dar\u00fcber hinaus die <a href=\"https:\/\/stabnau.com\/de\/vertriebsstrategie\/\" target=\"_blank\" rel=\"noopener noreferrer\">Zufriedenheit<\/a> in Form von positiver Emotion. Die Zufriedenheit, gefunden zu haben, die Zufriedenheit, verkauft zu haben, aber auch die Zufriedenheit, seinen Kunden zufrieden gestellt zu haben. Wenn man ein gutes Essen zubereitet, kann man es alleine essen. Man kann sich so viel bedienen, wie man will, bis einem schlecht wird. Aber am Ende wird dieses Essen immer besser schmecken, wenn es mit mehreren Personen geteilt wird, auch und vor allem, wenn der Kuchen geteilt wird.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die neuen Generationen haben dies verstanden und arbeiten bereits auf diese Weise. Denn gemeinsam sind wir immer st\u00e4rker als allein. Die Idee einer Person plus die Idee einer anderen Person l\u00e4sst mindestens eine dritte Idee aufkommen, wenn nicht mehr. Dank neuer digitaler Werkzeuge, wie z.B. Kollaborationsplattformen, ist es einfacher, an gemeinsamen Projekten <strong>kollaborativ zusammenzuarbeiten<\/strong>. Ideen zirkulieren und werden geteilt. Diese Arbeitsweise f\u00f6rdert die Innovation und die technologische <a href=\"https:\/\/stabnau.com\/de\/business-development\/\" target=\"_blank\" rel=\"noopener noreferrer\">Entwicklung<\/a> beschleunigt sich.<\/p>\n<p><\/p>\n<p><\/p>\n<p><strong>Transversalit\u00e4t<\/strong> ist wichtig, weil sie neue Ideen erm\u00f6glicht und die T\u00fcr zu Innovationen \u00f6ffnet. Die Transversalit\u00e4t wird an Bedeutung gewinnen, denn nach vielen Jahren der Spezialisierung und der zunehmenden Komplexit\u00e4t aller Gesch\u00e4ftsbereiche h\u00e4ngt der Erfolg eines Projekts, eines Unternehmens oder einer <a href=\"https:\/\/stabnau.com\/de\/organisation\/\" target=\"_blank\" rel=\"noopener noreferrer\">Organisation<\/a> von der guten Zusammenarbeit der Menschen ab. Die Transversalit\u00e4t schafft die Verbindung. Die Verbindung der verschiedenen Elemente, Bestandteile eines Ganzen, entscheidend f\u00fcr den reibungslosen Gesamtablauf und den Erfolg.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Als entscheidender Faktor der Wettbewerbsf\u00e4higkeit ist die <strong>Zeit<\/strong> geworden. Wie viel Zeit verbringen Sie pro Tag mit dem Lesen Ihrer E-Mails? Wie viele davon sind wirklich wichtig? Dasselbe gilt f\u00fcr Ihre Kollegen und Mitarbeiter. Wenn man sich auf Aufgaben, Projektfortschritt und das Endziel konzentriert, werden viele Nachrichten \u00fcberfl\u00fcssig. Auch hier k\u00f6nnen dank digitaler Werkzeuge alle den Fortschritt eines Projekts, offene oder geschlossene Aufgaben einsehen, die Chronologie verfolgen und ohne E-Mails kommunizieren. <strong>Die Effizienz von Organisationen spielt sich im Zeitmanagement und in der Kommunikation ab.<\/strong> Ich bin davon \u00fcberzeugt, dass E-Mails in der Zukunft vor allem ein Mittel sein werden, um mit Menschen &#8222;ausserhalb&#8220; der Organisation, des Unternehmens, zu kommunizieren, so wie fr\u00fcher Briefe verschickt wurden.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die Globalisierung hat ihre Grenzen gezeigt, <strong>Lokal arbeiten<\/strong> ist eine Selbstverst\u00e4ndlichkeit geworden. Nicht aus Gr\u00fcnden des R\u00fcckzugs, sondern aus Gr\u00fcnden des gesunden Menschenverstandes. Es geht also nicht um die Bevorzugung von Nationalit\u00e4ten, was eine Diskriminierung w\u00e4re, sondern um die Beg\u00fcnstigung der <a href=\"https:\/\/stabnau.com\/de\/frankreich\/\" target=\"_blank\" rel=\"noopener noreferrer\">geographischen N\u00e4he<\/a> bei gleichzeitiger Weltoffenheit. Warum ein Produkt vom anderen Ende der Welt besorgen, wenn mein Nachbar es herstellt? Indem ich sein Produkt kaufe, unterst\u00fctze ich sein Unternehmen, erhalte ich lokale Arbeitspl\u00e4tze, st\u00e4rke ich die lokale Kaufkraft und damit potenzielle Kunden, die K\u00e4ufer meiner eigenen Produkte. Ein Circulus virtuosus, positiv f\u00fcr die lokale Gemeinschaft zu der ich geh\u00f6re. Wenn das gesuchte Produkt in der N\u00e4he nicht existiert, wird der Suchradius erweitert und falls erforderlich am anderen Ende der Welt gekauft. Der andere positive Effekt dieser Art des Konsums ist die Verringerung des CO2-Fu\u00dfabdrucks f\u00fcr unseren Planeten.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Und was ist mit dem Preis? Irgendwo wird es immer einen niedrigeren Preis geben, aber zu welchem Preis? Damit ein Preis geringer ist, muss die Qualit\u00e4t des Produkts niedriger sein und\/oder die Herstellungskosten m\u00fcssen gesenkt werden, wie z.B. die Arbeitsl\u00f6hne. Der Kauf von &#8222;billig&#8220; verursacht einen Teufelskreis: Standortverlagerung, Arbeitslosigkeit usw. Dar\u00fcber hinaus ist die Zufriedenheit, ein gutes Gesch\u00e4ft gemacht zu haben, oft k\u00fcrzer als die Frustration ein schlechtes Produkt gekauft zu haben. &nbsp;Konsumieren, ja, aber besser, indem <strong>Qualit\u00e4t zur Quantit\u00e4t bevorzugt wird<\/strong>.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die Zeit der Ausbeutung der nat\u00fcrlichen Ressourcen und der Verschwendung ist vorbei, sie muss durch eine &nbsp;<strong>nachhaltige und Kreislaufwirtschaft<\/strong> ersetzt werden, denn &#8222;nichts geht verloren, nichts wird geschaffen, alles wird umgewandelt&#8220; (Antoine Lavoisier 1789).<\/p>\n<p><\/p>\n<p><\/p>\n<p>Autor: <a href=\"https:\/\/stabnau.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Axel Stabnau<\/a><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die COVID-19-Pandemie hat uns bewusst gemacht, dass unsere Gesundheit sehr wichtig ist. Unsere Wirtschaft, der Motor unserer Gesellschaft, wurde hart getroffen und jetzt ist es an der Zeit, wieder auf Kurs zu kommen. Wir k\u00f6nnen so weitermachen, wie wir es bisher getan haben, oder einige Dinge verbessern. Bis jetzt basierte unser Wirtschaftssystem ausschlie\u00dflich auf monet\u00e4ren [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualitaet"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Business Next Level: Menschen, Wirtschaft und Umwelt<\/title>\n<meta name=\"description\" content=\"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stabnau.com\/de\/business-next-level\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Business Next Level: Menschen, Wirtschaft und Umwelt\" \/>\n<meta property=\"og:description\" content=\"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stabnau.com\/de\/business-next-level\/\" \/>\n<meta property=\"og:site_name\" content=\"Stabnau\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-16T12:11:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-09T10:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"921\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Axel Stabnau\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Axel Stabnau\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/\"},\"author\":{\"name\":\"Axel Stabnau\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#\\\/schema\\\/person\\\/d752e903e0ccd71580651ecb5200bf76\"},\"headline\":\"Business Next Level\",\"datePublished\":\"2020-06-16T12:11:58+00:00\",\"dateModified\":\"2020-12-09T10:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/\"},\"wordCount\":938,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Business-Next-Level-3.jpeg\",\"articleSection\":[\"Aktualit\u00e4t\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/\",\"url\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/\",\"name\":\"Business Next Level: Menschen, Wirtschaft und Umwelt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Business-Next-Level-3.jpeg\",\"datePublished\":\"2020-06-16T12:11:58+00:00\",\"dateModified\":\"2020-12-09T10:01:22+00:00\",\"description\":\"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#primaryimage\",\"url\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Business-Next-Level-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Business-Next-Level-3.jpeg\",\"width\":921,\"height\":627,\"caption\":\"Human - Business and Environment\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/business-next-level\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/stabnau.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Business Next Level\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/stabnau.com\\\/de\\\/\",\"name\":\"Stabnau\",\"description\":\"D\u00e9veloppement commercial franco-allemand\",\"publisher\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stabnau.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#organization\",\"name\":\"Stabnau\",\"url\":\"https:\\\/\\\/stabnau.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Stabnau_logo-Stabnau-Business-development.png\",\"contentUrl\":\"https:\\\/\\\/stabnau.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cropped-Stabnau_logo-Stabnau-Business-development.png\",\"width\":1601,\"height\":426,\"caption\":\"Stabnau\"},\"image\":{\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stabnau.com\\\/de\\\/#\\\/schema\\\/person\\\/d752e903e0ccd71580651ecb5200bf76\",\"name\":\"Axel Stabnau\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g\",\"caption\":\"Axel Stabnau\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Business Next Level: Menschen, Wirtschaft und Umwelt","description":"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stabnau.com\/de\/business-next-level\/","og_locale":"de_DE","og_type":"article","og_title":"Business Next Level: Menschen, Wirtschaft und Umwelt","og_description":"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.","og_url":"https:\/\/stabnau.com\/de\/business-next-level\/","og_site_name":"Stabnau","article_published_time":"2020-06-16T12:11:58+00:00","article_modified_time":"2020-12-09T10:01:22+00:00","og_image":[{"width":921,"height":627,"url":"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg","type":"image\/jpeg"}],"author":"Axel Stabnau","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Axel Stabnau","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stabnau.com\/de\/business-next-level\/#article","isPartOf":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/"},"author":{"name":"Axel Stabnau","@id":"https:\/\/stabnau.com\/de\/#\/schema\/person\/d752e903e0ccd71580651ecb5200bf76"},"headline":"Business Next Level","datePublished":"2020-06-16T12:11:58+00:00","dateModified":"2020-12-09T10:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/"},"wordCount":938,"commentCount":0,"publisher":{"@id":"https:\/\/stabnau.com\/de\/#organization"},"image":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/#primaryimage"},"thumbnailUrl":"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg","articleSection":["Aktualit\u00e4t"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stabnau.com\/de\/business-next-level\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stabnau.com\/de\/business-next-level\/","url":"https:\/\/stabnau.com\/de\/business-next-level\/","name":"Business Next Level: Menschen, Wirtschaft und Umwelt","isPartOf":{"@id":"https:\/\/stabnau.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/#primaryimage"},"image":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/#primaryimage"},"thumbnailUrl":"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg","datePublished":"2020-06-16T12:11:58+00:00","dateModified":"2020-12-09T10:01:22+00:00","description":"Unternehmensentwicklung, Motor f\u00fcr Innovation und Wachstum. Nachhaltigkeit, Kreislaufwirtschaft. Solidarische und lokale Wirtschaft.","breadcrumb":{"@id":"https:\/\/stabnau.com\/de\/business-next-level\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stabnau.com\/de\/business-next-level\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stabnau.com\/de\/business-next-level\/#primaryimage","url":"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg","contentUrl":"https:\/\/stabnau.com\/wp-content\/uploads\/2020\/06\/Business-Next-Level-3.jpeg","width":921,"height":627,"caption":"Human - Business and Environment"},{"@type":"BreadcrumbList","@id":"https:\/\/stabnau.com\/de\/business-next-level\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/stabnau.com\/de\/"},{"@type":"ListItem","position":2,"name":"Business Next Level"}]},{"@type":"WebSite","@id":"https:\/\/stabnau.com\/de\/#website","url":"https:\/\/stabnau.com\/de\/","name":"Stabnau","description":"D\u00e9veloppement commercial franco-allemand","publisher":{"@id":"https:\/\/stabnau.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stabnau.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/stabnau.com\/de\/#organization","name":"Stabnau","url":"https:\/\/stabnau.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stabnau.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/stabnau.com\/wp-content\/uploads\/2022\/01\/cropped-Stabnau_logo-Stabnau-Business-development.png","contentUrl":"https:\/\/stabnau.com\/wp-content\/uploads\/2022\/01\/cropped-Stabnau_logo-Stabnau-Business-development.png","width":1601,"height":426,"caption":"Stabnau"},"image":{"@id":"https:\/\/stabnau.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/stabnau.com\/de\/#\/schema\/person\/d752e903e0ccd71580651ecb5200bf76","name":"Axel Stabnau","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/04358a10e5d6a699bcd9a9431e448033a292a47049965dd9a3287adf98fb2ece?s=96&d=mm&r=g","caption":"Axel Stabnau"}}]}},"_links":{"self":[{"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/posts\/2079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/comments?post=2079"}],"version-history":[{"count":0,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/posts\/2079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/media\/2078"}],"wp:attachment":[{"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/media?parent=2079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/categories?post=2079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stabnau.com\/de\/wp-json\/wp\/v2\/tags?post=2079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}